{"id":129,"date":"2024-06-14T17:42:21","date_gmt":"2024-06-14T15:42:21","guid":{"rendered":"https:\/\/cuisine.elodieduche.fr\/?p=129"},"modified":"2024-07-19T10:16:37","modified_gmt":"2024-07-19T08:16:37","slug":"tagliatelles-crevettes-chorizo","status":"publish","type":"post","link":"https:\/\/cuisine.elodieduche.fr\/index.php\/2024\/06\/14\/tagliatelles-crevettes-chorizo\/","title":{"rendered":"Tagliatelles crevettes &#038; chorizo"},"content":{"rendered":"<p>Bonjour \u00e0 tous,<\/p>\n<p>Je vous propose aujourd\u2019hui une recette sal\u00e9 des tagliatelles crevettes et chorizo !<\/p>\n<p>Pour 2 personnes, temps de pr\u00e9paration : 5 min, cuisson : 10 min<\/p>\n<h4>INGR\u00c9DIENTS:<\/h4>\n<ul>\n<li>140 g de tagliatelles<\/li>\n<li>160 g de crevette cuite<\/li>\n<li>2 c a soupe de cr\u00e8me de soja<\/li>\n<li>50 g de chorizo<\/li>\n<li>120 g de petit pois<\/li>\n<\/ul>\n<h4>ETAPES DE LA RECETTE:<\/h4>\n<ol>\n<li>Faites cuire les tagliatelles dans une eau bouillante sal\u00e9e selon les instructions de pr\u00e9paration (environ 8 minutes). \u00c9gouttez en fin de cuisson.<\/li>\n<li>Pendant ce temps, enlevez la peau du chorizo si vous le souhaitez et coupez-le en fines tranches.<\/li>\n<li>Dans une po\u00eale, ajoutez les crevettes, le chorizo et m\u00e9langez pendant 2 minutes \u00e0 feu vif.<\/li>\n<li>Ajoutez les petits pois et la cr\u00e8me fra\u00eeche, salez et poivrez. M\u00e9langez et faites cuire 3 minutes sur feu moyen.<\/li>\n<li>Ajoutez les tagliatelles dans la po\u00eale et m\u00e9langez.<\/li>\n<li>Servez et c&rsquo;est pr\u00eat !\n<div class=\"jow_prod__sc-e79981ff-0 bVOcRG jow_prod__sc-cba3a73c-22 eKSDrK\">\n<div class=\"jow_prod__sc-e79981ff-1 kxpyUg\"><\/div>\n<\/div>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous, Je vous propose aujourd\u2019hui une recette sal\u00e9 des tagliatelles crevettes et chorizo ! Pour 2 personnes, temps de pr\u00e9paration : 5 min, cuisson : 10 min INGR\u00c9DIENTS: 140 g de tagliatelles 160 g de crevette cuite 2 c a soupe de cr\u00e8me&nbsp;<a class=\"read-more\" href=\"https:\/\/cuisine.elodieduche.fr\/index.php\/2024\/06\/14\/tagliatelles-crevettes-chorizo\/\">&hellip;<\/a><\/p>\n","protected":false},"author":1,"featured_media":139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,3],"tags":[],"class_list":["post-129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes-salees","category-sans-lactose"],"_links":{"self":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":1,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"predecessor-version":[{"id":131,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts\/129\/revisions\/131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/media\/139"}],"wp:attachment":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}