{"id":91,"date":"2023-06-02T21:14:14","date_gmt":"2023-06-02T19:14:14","guid":{"rendered":"https:\/\/cuisine.elodieduche.fr\/?p=91"},"modified":"2023-06-02T21:14:14","modified_gmt":"2023-06-02T19:14:14","slug":"tarte-courgette-chevre","status":"publish","type":"post","link":"https:\/\/cuisine.elodieduche.fr\/index.php\/2023\/06\/02\/tarte-courgette-chevre\/","title":{"rendered":"Tarte courgette ch\u00e8vre"},"content":{"rendered":"<p>Bonjour \u00e0 tous,<\/p>\n<p>Je vous propose aujourd\u2019hui une recette sal\u00e9, une tarte courgette et ch\u00e8vre, sans lactose.<\/p>\n<h4>INGR\u00c9DIENTS:<\/h4>\n<ul>\n<li>P\u00e2te feuillet\u00e9 sans lactose (Celle de Herta sont extra)<\/li>\n<li>20 cl de cr\u00e8me de soja<\/li>\n<li>Une b\u00fbche de ch\u00e8vre<\/li>\n<li>Une cuill\u00e8re \u00e0 soupe de moutarde<\/li>\n<li>2 courgettes<\/li>\n<\/ul>\n<h4>ETAPES DE LA RECETTE:<\/h4>\n<ol>\n<li>Pr\u00e9chauffez le four \u00e0 200\u00b0C<\/li>\n<li>Coupez les courgettes en fines rondelles ainsi que la b\u00fbche de ch\u00e8vre.<\/li>\n<li>Garnir le moule \u00e0 tarte avec la p\u00e2te feuillet\u00e9, \u00e0 l&rsquo;aide d&rsquo;une fourchette piquez la p\u00e2te \u00e0 tarte et enfournez 5min.<\/li>\n<li>Sortez la p\u00e2te du four. Etalez l&rsquo;\u00e9quivalent d&rsquo;une cuill\u00e8re de moutarde dans le fond de la tarte.<\/li>\n<li>Disposez les rondelles de courgettes. Ajoutez les morceaux de ch\u00e8vre sur le dessus.<\/li>\n<li>Dans un bol, m\u00e9langez la cr\u00e8me de soja avec du sel et du poivre. Ajoutez le m\u00e9lange sur la tarte.<\/li>\n<li>Enfournez 30 \u00e0 40min.<\/li>\n<\/ol>\n<p>Plus qu&rsquo;a d\u00e9guster!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-93\" src=\"https:\/\/cuisine.elodieduche.fr\/wp-content\/uploads\/2023\/06\/Design-sans-titre-2-300x213.jpg\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/cuisine.elodieduche.fr\/wp-content\/uploads\/2023\/06\/Design-sans-titre-2-300x213.jpg 300w, https:\/\/cuisine.elodieduche.fr\/wp-content\/uploads\/2023\/06\/Design-sans-titre-2-1024x726.jpg 1024w, https:\/\/cuisine.elodieduche.fr\/wp-content\/uploads\/2023\/06\/Design-sans-titre-2-768x545.jpg 768w, https:\/\/cuisine.elodieduche.fr\/wp-content\/uploads\/2023\/06\/Design-sans-titre-2-1536x1090.jpg 1536w, https:\/\/cuisine.elodieduche.fr\/wp-content\/uploads\/2023\/06\/Design-sans-titre-2.jpg 1748w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous, Je vous propose aujourd\u2019hui une recette sal\u00e9, une tarte courgette et ch\u00e8vre, sans lactose. INGR\u00c9DIENTS: P\u00e2te feuillet\u00e9 sans lactose (Celle de Herta sont extra) 20 cl de cr\u00e8me de soja Une b\u00fbche de ch\u00e8vre Une cuill\u00e8re \u00e0 soupe de moutarde 2 courgettes&nbsp;<a class=\"read-more\" href=\"https:\/\/cuisine.elodieduche.fr\/index.php\/2023\/06\/02\/tarte-courgette-chevre\/\">&hellip;<\/a><\/p>\n","protected":false},"author":1,"featured_media":92,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,3],"tags":[],"class_list":["post-91","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes-salees","category-sans-lactose"],"_links":{"self":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":1,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts\/91\/revisions"}],"predecessor-version":[{"id":94,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/posts\/91\/revisions\/94"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/media\/92"}],"wp:attachment":[{"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/categories?post=91"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cuisine.elodieduche.fr\/index.php\/wp-json\/wp\/v2\/tags?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}